{"id":656,"date":"2012-10-01T13:37:08","date_gmt":"2012-10-01T12:37:08","guid":{"rendered":"http:\/\/www.fussball-fragen.de\/?p=656"},"modified":"2013-05-25T15:16:42","modified_gmt":"2013-05-25T14:16:42","slug":"wieviele-auswechslungen-sind-in-einem-testspiel-erlaubt","status":"publish","type":"post","link":"https:\/\/www.fussball-fragen.de\/index.php\/allgemein\/wieviele-auswechslungen-sind-in-einem-testspiel-erlaubt\/","title":{"rendered":"Wieviele Auswechslungen sind in einem Testspiel erlaubt?"},"content":{"rendered":"<p>Kann die Anzahl variieren?<\/p>\n<p><strong>Antwort:<\/strong><\/p>\n<p><a href=\"http:\/\/www.fussball-fragen.de\/index.php\/allgemein\/wieviele-auswechslungen-sind-in-einem-testspiel-erlaubt\/#comments\">Siehe Kommentar.<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Kann die Anzahl variieren? Antwort: Siehe Kommentar.<\/p>\n","protected":false},"author":65,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[25,23,320],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.1.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"Kann die Anzahl variieren? Antwort: Siehe Kommentar.\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Dopolski\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.fussball-fragen.de\/index.php\/allgemein\/wieviele-auswechslungen-sind-in-einem-testspiel-erlaubt\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.1.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"de_DE\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Fussball-Fragen\" \/>\n\t\t<meta property=\"og:type\" content=\"blog\" \/>\n\t\t<meta property=\"og:title\" content=\"Wieviele Auswechslungen sind in einem Testspiel erlaubt? | Fussball-Fragen\" \/>\n\t\t<meta property=\"og:description\" content=\"Kann die Anzahl variieren? Antwort: Siehe Kommentar.\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.fussball-fragen.de\/index.php\/allgemein\/wieviele-auswechslungen-sind-in-einem-testspiel-erlaubt\/\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Wieviele Auswechslungen sind in einem Testspiel erlaubt? | Fussball-Fragen\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Kann die Anzahl variieren? Antwort: Siehe Kommentar.\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.fussball-fragen.de\\\/index.php\\\/allgemein\\\/wieviele-auswechslungen-sind-in-einem-testspiel-erlaubt\\\/#article\",\"name\":\"Wieviele Auswechslungen sind in einem Testspiel erlaubt? | Fussball-Fragen\",\"headline\":\"Wieviele Auswechslungen sind in einem Testspiel erlaubt?\",\"author\":{\"@id\":\"https:\\\/\\\/www.fussball-fragen.de\\\/index.php\\\/author\\\/dopolski\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.fussball-fragen.de\\\/#organization\"},\"datePublished\":\"2012-10-01T13:37:08+02:00\",\"dateModified\":\"2013-05-25T15:16:42+02:00\",\"inLanguage\":\"de-DE\",\"commentCount\":1,\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.fussball-fragen.de\\\/index.php\\\/allgemein\\\/wieviele-auswechslungen-sind-in-einem-testspiel-erlaubt\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.fussball-fragen.de\\\/index.php\\\/allgemein\\\/wieviele-auswechslungen-sind-in-einem-testspiel-erlaubt\\\/#webpage\"},\"articleSection\":\"Allgemein, auswechseln, Auswechslung, Testspiel\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.fussball-fragen.de\\\/index.php\\\/allgemein\\\/wieviele-auswechslungen-sind-in-einem-testspiel-erlaubt\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.fussball-fragen.de#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.fussball-fragen.de\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.fussball-fragen.de\\\/index.php\\\/category\\\/allgemein\\\/#listItem\",\"name\":\"Allgemein\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.fussball-fragen.de\\\/index.php\\\/category\\\/allgemein\\\/#listItem\",\"position\":2,\"name\":\"Allgemein\",\"item\":\"https:\\\/\\\/www.fussball-fragen.de\\\/index.php\\\/category\\\/allgemein\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.fussball-fragen.de\\\/index.php\\\/allgemein\\\/wieviele-auswechslungen-sind-in-einem-testspiel-erlaubt\\\/#listItem\",\"name\":\"Wieviele Auswechslungen sind in einem Testspiel erlaubt?\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.fussball-fragen.de#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.fussball-fragen.de\\\/index.php\\\/allgemein\\\/wieviele-auswechslungen-sind-in-einem-testspiel-erlaubt\\\/#listItem\",\"position\":3,\"name\":\"Wieviele Auswechslungen sind in einem Testspiel erlaubt?\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.fussball-fragen.de\\\/index.php\\\/category\\\/allgemein\\\/#listItem\",\"name\":\"Allgemein\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.fussball-fragen.de\\\/#organization\",\"name\":\"Fussball-Fragen\",\"description\":\"Sinnvolles und sinnloses (Halb)wissen rund um den Fu\\u00dfball.\",\"url\":\"https:\\\/\\\/www.fussball-fragen.de\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.fussball-fragen.de\\\/index.php\\\/author\\\/dopolski\\\/#author\",\"url\":\"https:\\\/\\\/www.fussball-fragen.de\\\/index.php\\\/author\\\/dopolski\\\/\",\"name\":\"Dopolski\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.fussball-fragen.de\\\/index.php\\\/allgemein\\\/wieviele-auswechslungen-sind-in-einem-testspiel-erlaubt\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d1d64cdd773d033346cfe0cc14ca05fc?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Dopolski\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.fussball-fragen.de\\\/index.php\\\/allgemein\\\/wieviele-auswechslungen-sind-in-einem-testspiel-erlaubt\\\/#webpage\",\"url\":\"https:\\\/\\\/www.fussball-fragen.de\\\/index.php\\\/allgemein\\\/wieviele-auswechslungen-sind-in-einem-testspiel-erlaubt\\\/\",\"name\":\"Wieviele Auswechslungen sind in einem Testspiel erlaubt? | Fussball-Fragen\",\"description\":\"Kann die Anzahl variieren? Antwort: Siehe Kommentar.\",\"inLanguage\":\"de-DE\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.fussball-fragen.de\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.fussball-fragen.de\\\/index.php\\\/allgemein\\\/wieviele-auswechslungen-sind-in-einem-testspiel-erlaubt\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.fussball-fragen.de\\\/index.php\\\/author\\\/dopolski\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.fussball-fragen.de\\\/index.php\\\/author\\\/dopolski\\\/#author\"},\"datePublished\":\"2012-10-01T13:37:08+02:00\",\"dateModified\":\"2013-05-25T15:16:42+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.fussball-fragen.de\\\/#website\",\"url\":\"https:\\\/\\\/www.fussball-fragen.de\\\/\",\"name\":\"Fussball-Fragen\",\"description\":\"Sinnvolles und sinnloses (Halb)wissen rund um den Fu\\u00dfball.\",\"inLanguage\":\"de-DE\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.fussball-fragen.de\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Wieviele Auswechslungen sind in einem Testspiel erlaubt? | Fussball-Fragen","description":"Kann die Anzahl variieren? Antwort: Siehe Kommentar.","canonical_url":"https:\/\/www.fussball-fragen.de\/index.php\/allgemein\/wieviele-auswechslungen-sind-in-einem-testspiel-erlaubt\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.fussball-fragen.de\/index.php\/allgemein\/wieviele-auswechslungen-sind-in-einem-testspiel-erlaubt\/#article","name":"Wieviele Auswechslungen sind in einem Testspiel erlaubt? | Fussball-Fragen","headline":"Wieviele Auswechslungen sind in einem Testspiel erlaubt?","author":{"@id":"https:\/\/www.fussball-fragen.de\/index.php\/author\/dopolski\/#author"},"publisher":{"@id":"https:\/\/www.fussball-fragen.de\/#organization"},"datePublished":"2012-10-01T13:37:08+02:00","dateModified":"2013-05-25T15:16:42+02:00","inLanguage":"de-DE","commentCount":1,"mainEntityOfPage":{"@id":"https:\/\/www.fussball-fragen.de\/index.php\/allgemein\/wieviele-auswechslungen-sind-in-einem-testspiel-erlaubt\/#webpage"},"isPartOf":{"@id":"https:\/\/www.fussball-fragen.de\/index.php\/allgemein\/wieviele-auswechslungen-sind-in-einem-testspiel-erlaubt\/#webpage"},"articleSection":"Allgemein, auswechseln, Auswechslung, Testspiel"},{"@type":"BreadcrumbList","@id":"https:\/\/www.fussball-fragen.de\/index.php\/allgemein\/wieviele-auswechslungen-sind-in-einem-testspiel-erlaubt\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.fussball-fragen.de#listItem","position":1,"name":"Home","item":"https:\/\/www.fussball-fragen.de","nextItem":{"@type":"ListItem","@id":"https:\/\/www.fussball-fragen.de\/index.php\/category\/allgemein\/#listItem","name":"Allgemein"}},{"@type":"ListItem","@id":"https:\/\/www.fussball-fragen.de\/index.php\/category\/allgemein\/#listItem","position":2,"name":"Allgemein","item":"https:\/\/www.fussball-fragen.de\/index.php\/category\/allgemein\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.fussball-fragen.de\/index.php\/allgemein\/wieviele-auswechslungen-sind-in-einem-testspiel-erlaubt\/#listItem","name":"Wieviele Auswechslungen sind in einem Testspiel erlaubt?"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.fussball-fragen.de#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.fussball-fragen.de\/index.php\/allgemein\/wieviele-auswechslungen-sind-in-einem-testspiel-erlaubt\/#listItem","position":3,"name":"Wieviele Auswechslungen sind in einem Testspiel erlaubt?","previousItem":{"@type":"ListItem","@id":"https:\/\/www.fussball-fragen.de\/index.php\/category\/allgemein\/#listItem","name":"Allgemein"}}]},{"@type":"Organization","@id":"https:\/\/www.fussball-fragen.de\/#organization","name":"Fussball-Fragen","description":"Sinnvolles und sinnloses (Halb)wissen rund um den Fu\u00dfball.","url":"https:\/\/www.fussball-fragen.de\/"},{"@type":"Person","@id":"https:\/\/www.fussball-fragen.de\/index.php\/author\/dopolski\/#author","url":"https:\/\/www.fussball-fragen.de\/index.php\/author\/dopolski\/","name":"Dopolski","image":{"@type":"ImageObject","@id":"https:\/\/www.fussball-fragen.de\/index.php\/allgemein\/wieviele-auswechslungen-sind-in-einem-testspiel-erlaubt\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/d1d64cdd773d033346cfe0cc14ca05fc?s=96&d=mm&r=g","width":96,"height":96,"caption":"Dopolski"}},{"@type":"WebPage","@id":"https:\/\/www.fussball-fragen.de\/index.php\/allgemein\/wieviele-auswechslungen-sind-in-einem-testspiel-erlaubt\/#webpage","url":"https:\/\/www.fussball-fragen.de\/index.php\/allgemein\/wieviele-auswechslungen-sind-in-einem-testspiel-erlaubt\/","name":"Wieviele Auswechslungen sind in einem Testspiel erlaubt? | Fussball-Fragen","description":"Kann die Anzahl variieren? Antwort: Siehe Kommentar.","inLanguage":"de-DE","isPartOf":{"@id":"https:\/\/www.fussball-fragen.de\/#website"},"breadcrumb":{"@id":"https:\/\/www.fussball-fragen.de\/index.php\/allgemein\/wieviele-auswechslungen-sind-in-einem-testspiel-erlaubt\/#breadcrumblist"},"author":{"@id":"https:\/\/www.fussball-fragen.de\/index.php\/author\/dopolski\/#author"},"creator":{"@id":"https:\/\/www.fussball-fragen.de\/index.php\/author\/dopolski\/#author"},"datePublished":"2012-10-01T13:37:08+02:00","dateModified":"2013-05-25T15:16:42+02:00"},{"@type":"WebSite","@id":"https:\/\/www.fussball-fragen.de\/#website","url":"https:\/\/www.fussball-fragen.de\/","name":"Fussball-Fragen","description":"Sinnvolles und sinnloses (Halb)wissen rund um den Fu\u00dfball.","inLanguage":"de-DE","publisher":{"@id":"https:\/\/www.fussball-fragen.de\/#organization"}}]},"og:locale":"de_DE","og:site_name":"Fussball-Fragen","og:type":"blog","og:title":"Wieviele Auswechslungen sind in einem Testspiel erlaubt? | Fussball-Fragen","og:description":"Kann die Anzahl variieren? Antwort: Siehe Kommentar.","og:url":"https:\/\/www.fussball-fragen.de\/index.php\/allgemein\/wieviele-auswechslungen-sind-in-einem-testspiel-erlaubt\/","twitter:card":"summary","twitter:title":"Wieviele Auswechslungen sind in einem Testspiel erlaubt? | Fussball-Fragen","twitter:description":"Kann die Anzahl variieren? Antwort: Siehe Kommentar."},"aioseo_meta_data":{"post_id":"656","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2021-12-24 14:14:34","updated":"2022-09-14 11:21:18","seo_analyzer_scan_date":null,"focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.fussball-fragen.de\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.fussball-fragen.de\/index.php\/category\/allgemein\/\" title=\"Allgemein\">Allgemein<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tWieviele Auswechslungen sind in einem Testspiel erlaubt?\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.fussball-fragen.de"},{"label":"Allgemein","link":"https:\/\/www.fussball-fragen.de\/index.php\/category\/allgemein\/"},{"label":"Wieviele Auswechslungen sind in einem Testspiel erlaubt?","link":"https:\/\/www.fussball-fragen.de\/index.php\/allgemein\/wieviele-auswechslungen-sind-in-einem-testspiel-erlaubt\/"}],"views":5872,"_links":{"self":[{"href":"https:\/\/www.fussball-fragen.de\/index.php\/wp-json\/wp\/v2\/posts\/656"}],"collection":[{"href":"https:\/\/www.fussball-fragen.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fussball-fragen.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fussball-fragen.de\/index.php\/wp-json\/wp\/v2\/users\/65"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fussball-fragen.de\/index.php\/wp-json\/wp\/v2\/comments?post=656"}],"version-history":[{"count":3,"href":"https:\/\/www.fussball-fragen.de\/index.php\/wp-json\/wp\/v2\/posts\/656\/revisions"}],"predecessor-version":[{"id":1139,"href":"https:\/\/www.fussball-fragen.de\/index.php\/wp-json\/wp\/v2\/posts\/656\/revisions\/1139"}],"wp:attachment":[{"href":"https:\/\/www.fussball-fragen.de\/index.php\/wp-json\/wp\/v2\/media?parent=656"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fussball-fragen.de\/index.php\/wp-json\/wp\/v2\/categories?post=656"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fussball-fragen.de\/index.php\/wp-json\/wp\/v2\/tags?post=656"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}