{"id":3874,"date":"2015-10-31T14:47:20","date_gmt":"2015-10-31T13:47:20","guid":{"rendered":"http:\/\/www.fussball-fragen.de\/?p=3874"},"modified":"2015-11-06T08:36:33","modified_gmt":"2015-11-06T07:36:33","slug":"wie-viel-prozent-der-deutschen-spielen-fussball","status":"publish","type":"post","link":"https:\/\/www.fussball-fragen.de\/index.php\/deutschland\/wie-viel-prozent-der-deutschen-spielen-fussball\/","title":{"rendered":"Wie viel Prozent der Deutschen spielen Fussball?"},"content":{"rendered":"<p><strong>Frage:<\/strong><\/p>\n<p>Wieviel Prozent der Deutschen spielen Fussball?<\/p>\n<p><strong>Antwort:<\/strong><\/p>\n<p>Aktuell sind beim DFB <a href=\"http:\/\/www.dfb.de\/verbandsstruktur\/mitglieder\/\" target=\"_blank\">6.889.115 Spieler gemeldet<\/a> (Stand 2015), die Gesamtbev\u00f6lkerung im Jahr <a href=\"http:\/\/de.statista.com\/themen\/20\/einwohnerzahl\/\" target=\"_blank\">2014 waren 81,2 Millionen<\/a>. Daher spielen etwa 11% (genau 11,786%) der Bev\u00f6lkerung Fu\u00dfball in Vereinen.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Frage: Wieviel Prozent der Deutschen spielen Fussball? Antwort: Aktuell sind beim DFB 6.889.115 Spieler gemeldet (Stand 2015), die Gesamtbev\u00f6lkerung im Jahr 2014 waren 81,2 Millionen. Daher spielen etwa 11% (genau 11,786%) der&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[1254,1287,1255],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.1.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"Frage: Wieviel Prozent der Deutschen spielen Fussball? Antwort: Aktuell sind beim DFB 6.889.115 Spieler gemeldet (Stand 2015), die Gesamtbev\u00f6lkerung im Jahr 2014 waren 81,2 Millionen. Daher spielen etwa 11% (genau 11,786%) der Bev\u00f6lkerung Fu\u00dfball in Vereinen.\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"ff-admin\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.fussball-fragen.de\/index.php\/deutschland\/wie-viel-prozent-der-deutschen-spielen-fussball\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.1.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"de_DE\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Fussball-Fragen\" \/>\n\t\t<meta property=\"og:type\" content=\"blog\" \/>\n\t\t<meta property=\"og:title\" content=\"Wie viel Prozent der Deutschen spielen Fussball? | Fussball-Fragen\" \/>\n\t\t<meta property=\"og:description\" content=\"Frage: Wieviel Prozent der Deutschen spielen Fussball? Antwort: Aktuell sind beim DFB 6.889.115 Spieler gemeldet (Stand 2015), die Gesamtbev\u00f6lkerung im Jahr 2014 waren 81,2 Millionen. Daher spielen etwa 11% (genau 11,786%) der Bev\u00f6lkerung Fu\u00dfball in Vereinen.\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.fussball-fragen.de\/index.php\/deutschland\/wie-viel-prozent-der-deutschen-spielen-fussball\/\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Wie viel Prozent der Deutschen spielen Fussball? | Fussball-Fragen\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Frage: Wieviel Prozent der Deutschen spielen Fussball? Antwort: Aktuell sind beim DFB 6.889.115 Spieler gemeldet (Stand 2015), die Gesamtbev\u00f6lkerung im Jahr 2014 waren 81,2 Millionen. Daher spielen etwa 11% (genau 11,786%) der Bev\u00f6lkerung Fu\u00dfball in Vereinen.\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.fussball-fragen.de\\\/index.php\\\/deutschland\\\/wie-viel-prozent-der-deutschen-spielen-fussball\\\/#article\",\"name\":\"Wie viel Prozent der Deutschen spielen Fussball? | Fussball-Fragen\",\"headline\":\"Wie viel Prozent der Deutschen spielen Fussball?\",\"author\":{\"@id\":\"https:\\\/\\\/www.fussball-fragen.de\\\/index.php\\\/author\\\/ff-admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.fussball-fragen.de\\\/#organization\"},\"datePublished\":\"2015-10-31T14:47:20+01:00\",\"dateModified\":\"2015-11-06T08:36:33+01:00\",\"inLanguage\":\"de-DE\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.fussball-fragen.de\\\/index.php\\\/deutschland\\\/wie-viel-prozent-der-deutschen-spielen-fussball\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.fussball-fragen.de\\\/index.php\\\/deutschland\\\/wie-viel-prozent-der-deutschen-spielen-fussball\\\/#webpage\"},\"articleSection\":\"Deutschland, Deutschland, Prozent, Spieler\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.fussball-fragen.de\\\/index.php\\\/deutschland\\\/wie-viel-prozent-der-deutschen-spielen-fussball\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.fussball-fragen.de#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.fussball-fragen.de\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.fussball-fragen.de\\\/index.php\\\/category\\\/deutschland\\\/#listItem\",\"name\":\"Deutschland\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.fussball-fragen.de\\\/index.php\\\/category\\\/deutschland\\\/#listItem\",\"position\":2,\"name\":\"Deutschland\",\"item\":\"https:\\\/\\\/www.fussball-fragen.de\\\/index.php\\\/category\\\/deutschland\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.fussball-fragen.de\\\/index.php\\\/deutschland\\\/wie-viel-prozent-der-deutschen-spielen-fussball\\\/#listItem\",\"name\":\"Wie viel Prozent der Deutschen spielen Fussball?\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.fussball-fragen.de#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.fussball-fragen.de\\\/index.php\\\/deutschland\\\/wie-viel-prozent-der-deutschen-spielen-fussball\\\/#listItem\",\"position\":3,\"name\":\"Wie viel Prozent der Deutschen spielen Fussball?\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.fussball-fragen.de\\\/index.php\\\/category\\\/deutschland\\\/#listItem\",\"name\":\"Deutschland\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.fussball-fragen.de\\\/#organization\",\"name\":\"Fussball-Fragen\",\"description\":\"Sinnvolles und sinnloses (Halb)wissen rund um den Fu\\u00dfball.\",\"url\":\"https:\\\/\\\/www.fussball-fragen.de\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.fussball-fragen.de\\\/index.php\\\/author\\\/ff-admin\\\/#author\",\"url\":\"https:\\\/\\\/www.fussball-fragen.de\\\/index.php\\\/author\\\/ff-admin\\\/\",\"name\":\"ff-admin\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.fussball-fragen.de\\\/index.php\\\/deutschland\\\/wie-viel-prozent-der-deutschen-spielen-fussball\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a8b0a04952980de24adc2a8820b0c592?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"ff-admin\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.fussball-fragen.de\\\/index.php\\\/deutschland\\\/wie-viel-prozent-der-deutschen-spielen-fussball\\\/#webpage\",\"url\":\"https:\\\/\\\/www.fussball-fragen.de\\\/index.php\\\/deutschland\\\/wie-viel-prozent-der-deutschen-spielen-fussball\\\/\",\"name\":\"Wie viel Prozent der Deutschen spielen Fussball? | Fussball-Fragen\",\"description\":\"Frage: Wieviel Prozent der Deutschen spielen Fussball? Antwort: Aktuell sind beim DFB 6.889.115 Spieler gemeldet (Stand 2015), die Gesamtbev\\u00f6lkerung im Jahr 2014 waren 81,2 Millionen. Daher spielen etwa 11% (genau 11,786%) der Bev\\u00f6lkerung Fu\\u00dfball in Vereinen.\",\"inLanguage\":\"de-DE\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.fussball-fragen.de\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.fussball-fragen.de\\\/index.php\\\/deutschland\\\/wie-viel-prozent-der-deutschen-spielen-fussball\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.fussball-fragen.de\\\/index.php\\\/author\\\/ff-admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.fussball-fragen.de\\\/index.php\\\/author\\\/ff-admin\\\/#author\"},\"datePublished\":\"2015-10-31T14:47:20+01:00\",\"dateModified\":\"2015-11-06T08:36:33+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.fussball-fragen.de\\\/#website\",\"url\":\"https:\\\/\\\/www.fussball-fragen.de\\\/\",\"name\":\"Fussball-Fragen\",\"description\":\"Sinnvolles und sinnloses (Halb)wissen rund um den Fu\\u00dfball.\",\"inLanguage\":\"de-DE\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.fussball-fragen.de\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Wie viel Prozent der Deutschen spielen Fussball? | Fussball-Fragen","description":"Frage: Wieviel Prozent der Deutschen spielen Fussball? Antwort: Aktuell sind beim DFB 6.889.115 Spieler gemeldet (Stand 2015), die Gesamtbev\u00f6lkerung im Jahr 2014 waren 81,2 Millionen. Daher spielen etwa 11% (genau 11,786%) der Bev\u00f6lkerung Fu\u00dfball in Vereinen.","canonical_url":"https:\/\/www.fussball-fragen.de\/index.php\/deutschland\/wie-viel-prozent-der-deutschen-spielen-fussball\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.fussball-fragen.de\/index.php\/deutschland\/wie-viel-prozent-der-deutschen-spielen-fussball\/#article","name":"Wie viel Prozent der Deutschen spielen Fussball? | Fussball-Fragen","headline":"Wie viel Prozent der Deutschen spielen Fussball?","author":{"@id":"https:\/\/www.fussball-fragen.de\/index.php\/author\/ff-admin\/#author"},"publisher":{"@id":"https:\/\/www.fussball-fragen.de\/#organization"},"datePublished":"2015-10-31T14:47:20+01:00","dateModified":"2015-11-06T08:36:33+01:00","inLanguage":"de-DE","mainEntityOfPage":{"@id":"https:\/\/www.fussball-fragen.de\/index.php\/deutschland\/wie-viel-prozent-der-deutschen-spielen-fussball\/#webpage"},"isPartOf":{"@id":"https:\/\/www.fussball-fragen.de\/index.php\/deutschland\/wie-viel-prozent-der-deutschen-spielen-fussball\/#webpage"},"articleSection":"Deutschland, Deutschland, Prozent, Spieler"},{"@type":"BreadcrumbList","@id":"https:\/\/www.fussball-fragen.de\/index.php\/deutschland\/wie-viel-prozent-der-deutschen-spielen-fussball\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.fussball-fragen.de#listItem","position":1,"name":"Home","item":"https:\/\/www.fussball-fragen.de","nextItem":{"@type":"ListItem","@id":"https:\/\/www.fussball-fragen.de\/index.php\/category\/deutschland\/#listItem","name":"Deutschland"}},{"@type":"ListItem","@id":"https:\/\/www.fussball-fragen.de\/index.php\/category\/deutschland\/#listItem","position":2,"name":"Deutschland","item":"https:\/\/www.fussball-fragen.de\/index.php\/category\/deutschland\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.fussball-fragen.de\/index.php\/deutschland\/wie-viel-prozent-der-deutschen-spielen-fussball\/#listItem","name":"Wie viel Prozent der Deutschen spielen Fussball?"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.fussball-fragen.de#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.fussball-fragen.de\/index.php\/deutschland\/wie-viel-prozent-der-deutschen-spielen-fussball\/#listItem","position":3,"name":"Wie viel Prozent der Deutschen spielen Fussball?","previousItem":{"@type":"ListItem","@id":"https:\/\/www.fussball-fragen.de\/index.php\/category\/deutschland\/#listItem","name":"Deutschland"}}]},{"@type":"Organization","@id":"https:\/\/www.fussball-fragen.de\/#organization","name":"Fussball-Fragen","description":"Sinnvolles und sinnloses (Halb)wissen rund um den Fu\u00dfball.","url":"https:\/\/www.fussball-fragen.de\/"},{"@type":"Person","@id":"https:\/\/www.fussball-fragen.de\/index.php\/author\/ff-admin\/#author","url":"https:\/\/www.fussball-fragen.de\/index.php\/author\/ff-admin\/","name":"ff-admin","image":{"@type":"ImageObject","@id":"https:\/\/www.fussball-fragen.de\/index.php\/deutschland\/wie-viel-prozent-der-deutschen-spielen-fussball\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/a8b0a04952980de24adc2a8820b0c592?s=96&d=mm&r=g","width":96,"height":96,"caption":"ff-admin"}},{"@type":"WebPage","@id":"https:\/\/www.fussball-fragen.de\/index.php\/deutschland\/wie-viel-prozent-der-deutschen-spielen-fussball\/#webpage","url":"https:\/\/www.fussball-fragen.de\/index.php\/deutschland\/wie-viel-prozent-der-deutschen-spielen-fussball\/","name":"Wie viel Prozent der Deutschen spielen Fussball? | Fussball-Fragen","description":"Frage: Wieviel Prozent der Deutschen spielen Fussball? Antwort: Aktuell sind beim DFB 6.889.115 Spieler gemeldet (Stand 2015), die Gesamtbev\u00f6lkerung im Jahr 2014 waren 81,2 Millionen. Daher spielen etwa 11% (genau 11,786%) der Bev\u00f6lkerung Fu\u00dfball in Vereinen.","inLanguage":"de-DE","isPartOf":{"@id":"https:\/\/www.fussball-fragen.de\/#website"},"breadcrumb":{"@id":"https:\/\/www.fussball-fragen.de\/index.php\/deutschland\/wie-viel-prozent-der-deutschen-spielen-fussball\/#breadcrumblist"},"author":{"@id":"https:\/\/www.fussball-fragen.de\/index.php\/author\/ff-admin\/#author"},"creator":{"@id":"https:\/\/www.fussball-fragen.de\/index.php\/author\/ff-admin\/#author"},"datePublished":"2015-10-31T14:47:20+01:00","dateModified":"2015-11-06T08:36:33+01:00"},{"@type":"WebSite","@id":"https:\/\/www.fussball-fragen.de\/#website","url":"https:\/\/www.fussball-fragen.de\/","name":"Fussball-Fragen","description":"Sinnvolles und sinnloses (Halb)wissen rund um den Fu\u00dfball.","inLanguage":"de-DE","publisher":{"@id":"https:\/\/www.fussball-fragen.de\/#organization"}}]},"og:locale":"de_DE","og:site_name":"Fussball-Fragen","og:type":"blog","og:title":"Wie viel Prozent der Deutschen spielen Fussball? | Fussball-Fragen","og:description":"Frage: Wieviel Prozent der Deutschen spielen Fussball? Antwort: Aktuell sind beim DFB 6.889.115 Spieler gemeldet (Stand 2015), die Gesamtbev\u00f6lkerung im Jahr 2014 waren 81,2 Millionen. Daher spielen etwa 11% (genau 11,786%) der Bev\u00f6lkerung Fu\u00dfball in Vereinen.","og:url":"https:\/\/www.fussball-fragen.de\/index.php\/deutschland\/wie-viel-prozent-der-deutschen-spielen-fussball\/","twitter:card":"summary","twitter:title":"Wie viel Prozent der Deutschen spielen Fussball? | Fussball-Fragen","twitter:description":"Frage: Wieviel Prozent der Deutschen spielen Fussball? Antwort: Aktuell sind beim DFB 6.889.115 Spieler gemeldet (Stand 2015), die Gesamtbev\u00f6lkerung im Jahr 2014 waren 81,2 Millionen. Daher spielen etwa 11% (genau 11,786%) der Bev\u00f6lkerung Fu\u00dfball in Vereinen."},"aioseo_meta_data":{"post_id":"3874","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":"","og_description":"","og_object_type":"blog","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":"","og_article_tags":"","twitter_use_og":false,"twitter_card":"summary","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2021-12-24 13:52:20","updated":"2022-09-14 21:09:32","seo_analyzer_scan_date":null,"focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.fussball-fragen.de\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.fussball-fragen.de\/index.php\/category\/deutschland\/\" title=\"Deutschland\">Deutschland<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tWie viel Prozent der Deutschen spielen Fussball?\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.fussball-fragen.de"},{"label":"Deutschland","link":"https:\/\/www.fussball-fragen.de\/index.php\/category\/deutschland\/"},{"label":"Wie viel Prozent der Deutschen spielen Fussball?","link":"https:\/\/www.fussball-fragen.de\/index.php\/deutschland\/wie-viel-prozent-der-deutschen-spielen-fussball\/"}],"views":3279,"_links":{"self":[{"href":"https:\/\/www.fussball-fragen.de\/index.php\/wp-json\/wp\/v2\/posts\/3874"}],"collection":[{"href":"https:\/\/www.fussball-fragen.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fussball-fragen.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fussball-fragen.de\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fussball-fragen.de\/index.php\/wp-json\/wp\/v2\/comments?post=3874"}],"version-history":[{"count":2,"href":"https:\/\/www.fussball-fragen.de\/index.php\/wp-json\/wp\/v2\/posts\/3874\/revisions"}],"predecessor-version":[{"id":3876,"href":"https:\/\/www.fussball-fragen.de\/index.php\/wp-json\/wp\/v2\/posts\/3874\/revisions\/3876"}],"wp:attachment":[{"href":"https:\/\/www.fussball-fragen.de\/index.php\/wp-json\/wp\/v2\/media?parent=3874"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fussball-fragen.de\/index.php\/wp-json\/wp\/v2\/categories?post=3874"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fussball-fragen.de\/index.php\/wp-json\/wp\/v2\/tags?post=3874"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}