{"id":1486,"date":"2013-07-19T14:58:58","date_gmt":"2013-07-19T13:58:58","guid":{"rendered":"http:\/\/www.fussball-fragen.de\/?p=1486"},"modified":"2013-07-20T12:18:05","modified_gmt":"2013-07-20T11:18:05","slug":"wie-oft-spielte-der-hamburger-sv-in-der-bundesliga-im-juli-um-punkte","status":"publish","type":"post","link":"https:\/\/www.fussball-fragen.de\/index.php\/bundesliga\/wie-oft-spielte-der-hamburger-sv-in-der-bundesliga-im-juli-um-punkte\/","title":{"rendered":"Wie oft spielte der Hamburger SV in der Bundesliga im Juli um Punkte?"},"content":{"rendered":"<p><strong>Frage:<\/strong><\/p>\n<p>Wie oft spielte HSV in der Bundesliga im Juli um Punkte?<\/p>\n<p><strong>Antwort:<\/strong><\/p>\n<p>Insgesamt nur 4x in der 50j\u00e4hrigen Bundesligazugeh\u00f6rigkeit (bei insgesamt 1696 Spielen in dieser Zeit):<\/p>\n<p>Saison 1988\/1989<br \/>\nSpieltag 1 (Sa. 23.07.1988) Werder Bremen &#8211; Hamburger SV 2:1<br \/>\nSpieltag 2 (Fr. 29.07.1988) Hamburger SV &#8211; Borussia Dortmund 0:0<\/p>\n<p>Saison 1989\/90<br \/>\nSpieltag 1 (Sa. 29.07.1989) Fortuna D\u00fcsseldorf &#8211; Hamburger SV 1:1<\/p>\n<p>Saison 2001\/02<br \/>\nSpieltag 1 (Sa. 28.07.2001) FC Energie Cottbus &#8211; Hamburger SV 1:0<\/p>\n<p>Quelle: <a href=\"http:\/\/www.bundesliga-statistik.de\/index.php?pos=erg_team\" target=\"_blank\">Fu\u00dfball-Bundesliga Statistik<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Frage: Wie oft spielte HSV in der Bundesliga im Juli um Punkte? Antwort: Insgesamt nur 4x in der 50j\u00e4hrigen Bundesligazugeh\u00f6rigkeit (bei insgesamt 1696 Spielen in dieser Zeit): Saison 1988\/1989 Spieltag 1 (Sa&#8230;.<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[1251,62,452,116],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.1.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"Frage: Wie oft spielte HSV in der Bundesliga im Juli um Punkte? Antwort: Insgesamt nur 4x in der 50j\u00e4hrigen Bundesligazugeh\u00f6rigkeit (bei insgesamt 1696 Spielen in dieser Zeit): Saison 1988\/1989 Spieltag 1 (Sa. 23.07.1988) Werder Bremen - Hamburger SV 2:1 Spieltag 2 (Fr. 29.07.1988) Hamburger SV - Borussia Dortmund 0:0 Saison 1989\/90 Spieltag 1 (Sa. 29.07.1989)\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"ff-admin\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.fussball-fragen.de\/index.php\/bundesliga\/wie-oft-spielte-der-hamburger-sv-in-der-bundesliga-im-juli-um-punkte\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.1.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"de_DE\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Fussball-Fragen\" \/>\n\t\t<meta property=\"og:type\" content=\"blog\" \/>\n\t\t<meta property=\"og:title\" content=\"Wie oft spielte der Hamburger SV in der Bundesliga im Juli um Punkte? | Fussball-Fragen\" \/>\n\t\t<meta property=\"og:description\" content=\"Frage: Wie oft spielte HSV in der Bundesliga im Juli um Punkte? Antwort: Insgesamt nur 4x in der 50j\u00e4hrigen Bundesligazugeh\u00f6rigkeit (bei insgesamt 1696 Spielen in dieser Zeit): Saison 1988\/1989 Spieltag 1 (Sa. 23.07.1988) Werder Bremen - Hamburger SV 2:1 Spieltag 2 (Fr. 29.07.1988) Hamburger SV - Borussia Dortmund 0:0 Saison 1989\/90 Spieltag 1 (Sa. 29.07.1989)\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.fussball-fragen.de\/index.php\/bundesliga\/wie-oft-spielte-der-hamburger-sv-in-der-bundesliga-im-juli-um-punkte\/\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Wie oft spielte der Hamburger SV in der Bundesliga im Juli um Punkte? | Fussball-Fragen\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Frage: Wie oft spielte HSV in der Bundesliga im Juli um Punkte? Antwort: Insgesamt nur 4x in der 50j\u00e4hrigen Bundesligazugeh\u00f6rigkeit (bei insgesamt 1696 Spielen in dieser Zeit): Saison 1988\/1989 Spieltag 1 (Sa. 23.07.1988) Werder Bremen - Hamburger SV 2:1 Spieltag 2 (Fr. 29.07.1988) Hamburger SV - Borussia Dortmund 0:0 Saison 1989\/90 Spieltag 1 (Sa. 29.07.1989)\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.fussball-fragen.de\\\/index.php\\\/bundesliga\\\/wie-oft-spielte-der-hamburger-sv-in-der-bundesliga-im-juli-um-punkte\\\/#article\",\"name\":\"Wie oft spielte der Hamburger SV in der Bundesliga im Juli um Punkte? | Fussball-Fragen\",\"headline\":\"Wie oft spielte der Hamburger SV in der Bundesliga im Juli um Punkte?\",\"author\":{\"@id\":\"https:\\\/\\\/www.fussball-fragen.de\\\/index.php\\\/author\\\/ff-admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.fussball-fragen.de\\\/#organization\"},\"datePublished\":\"2013-07-19T14:58:58+02:00\",\"dateModified\":\"2013-07-20T12:18:05+02:00\",\"inLanguage\":\"de-DE\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.fussball-fragen.de\\\/index.php\\\/bundesliga\\\/wie-oft-spielte-der-hamburger-sv-in-der-bundesliga-im-juli-um-punkte\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.fussball-fragen.de\\\/index.php\\\/bundesliga\\\/wie-oft-spielte-der-hamburger-sv-in-der-bundesliga-im-juli-um-punkte\\\/#webpage\"},\"articleSection\":\"Bundesliga, Bundesliga, Hamburger SV, HSV, Spiele\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.fussball-fragen.de\\\/index.php\\\/bundesliga\\\/wie-oft-spielte-der-hamburger-sv-in-der-bundesliga-im-juli-um-punkte\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.fussball-fragen.de#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.fussball-fragen.de\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.fussball-fragen.de\\\/index.php\\\/category\\\/bundesliga\\\/#listItem\",\"name\":\"Bundesliga\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.fussball-fragen.de\\\/index.php\\\/category\\\/bundesliga\\\/#listItem\",\"position\":2,\"name\":\"Bundesliga\",\"item\":\"https:\\\/\\\/www.fussball-fragen.de\\\/index.php\\\/category\\\/bundesliga\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.fussball-fragen.de\\\/index.php\\\/bundesliga\\\/wie-oft-spielte-der-hamburger-sv-in-der-bundesliga-im-juli-um-punkte\\\/#listItem\",\"name\":\"Wie oft spielte der Hamburger SV in der Bundesliga im Juli um Punkte?\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.fussball-fragen.de#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.fussball-fragen.de\\\/index.php\\\/bundesliga\\\/wie-oft-spielte-der-hamburger-sv-in-der-bundesliga-im-juli-um-punkte\\\/#listItem\",\"position\":3,\"name\":\"Wie oft spielte der Hamburger SV in der Bundesliga im Juli um Punkte?\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.fussball-fragen.de\\\/index.php\\\/category\\\/bundesliga\\\/#listItem\",\"name\":\"Bundesliga\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.fussball-fragen.de\\\/#organization\",\"name\":\"Fussball-Fragen\",\"description\":\"Sinnvolles und sinnloses (Halb)wissen rund um den Fu\\u00dfball.\",\"url\":\"https:\\\/\\\/www.fussball-fragen.de\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.fussball-fragen.de\\\/index.php\\\/author\\\/ff-admin\\\/#author\",\"url\":\"https:\\\/\\\/www.fussball-fragen.de\\\/index.php\\\/author\\\/ff-admin\\\/\",\"name\":\"ff-admin\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.fussball-fragen.de\\\/index.php\\\/bundesliga\\\/wie-oft-spielte-der-hamburger-sv-in-der-bundesliga-im-juli-um-punkte\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a8b0a04952980de24adc2a8820b0c592?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"ff-admin\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.fussball-fragen.de\\\/index.php\\\/bundesliga\\\/wie-oft-spielte-der-hamburger-sv-in-der-bundesliga-im-juli-um-punkte\\\/#webpage\",\"url\":\"https:\\\/\\\/www.fussball-fragen.de\\\/index.php\\\/bundesliga\\\/wie-oft-spielte-der-hamburger-sv-in-der-bundesliga-im-juli-um-punkte\\\/\",\"name\":\"Wie oft spielte der Hamburger SV in der Bundesliga im Juli um Punkte? | Fussball-Fragen\",\"description\":\"Frage: Wie oft spielte HSV in der Bundesliga im Juli um Punkte? Antwort: Insgesamt nur 4x in der 50j\\u00e4hrigen Bundesligazugeh\\u00f6rigkeit (bei insgesamt 1696 Spielen in dieser Zeit): Saison 1988\\\/1989 Spieltag 1 (Sa. 23.07.1988) Werder Bremen - Hamburger SV 2:1 Spieltag 2 (Fr. 29.07.1988) Hamburger SV - Borussia Dortmund 0:0 Saison 1989\\\/90 Spieltag 1 (Sa. 29.07.1989)\",\"inLanguage\":\"de-DE\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.fussball-fragen.de\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.fussball-fragen.de\\\/index.php\\\/bundesliga\\\/wie-oft-spielte-der-hamburger-sv-in-der-bundesliga-im-juli-um-punkte\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.fussball-fragen.de\\\/index.php\\\/author\\\/ff-admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.fussball-fragen.de\\\/index.php\\\/author\\\/ff-admin\\\/#author\"},\"datePublished\":\"2013-07-19T14:58:58+02:00\",\"dateModified\":\"2013-07-20T12:18:05+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.fussball-fragen.de\\\/#website\",\"url\":\"https:\\\/\\\/www.fussball-fragen.de\\\/\",\"name\":\"Fussball-Fragen\",\"description\":\"Sinnvolles und sinnloses (Halb)wissen rund um den Fu\\u00dfball.\",\"inLanguage\":\"de-DE\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.fussball-fragen.de\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Wie oft spielte der Hamburger SV in der Bundesliga im Juli um Punkte? | Fussball-Fragen","description":"Frage: Wie oft spielte HSV in der Bundesliga im Juli um Punkte? Antwort: Insgesamt nur 4x in der 50j\u00e4hrigen Bundesligazugeh\u00f6rigkeit (bei insgesamt 1696 Spielen in dieser Zeit): Saison 1988\/1989 Spieltag 1 (Sa. 23.07.1988) Werder Bremen - Hamburger SV 2:1 Spieltag 2 (Fr. 29.07.1988) Hamburger SV - Borussia Dortmund 0:0 Saison 1989\/90 Spieltag 1 (Sa. 29.07.1989)","canonical_url":"https:\/\/www.fussball-fragen.de\/index.php\/bundesliga\/wie-oft-spielte-der-hamburger-sv-in-der-bundesliga-im-juli-um-punkte\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.fussball-fragen.de\/index.php\/bundesliga\/wie-oft-spielte-der-hamburger-sv-in-der-bundesliga-im-juli-um-punkte\/#article","name":"Wie oft spielte der Hamburger SV in der Bundesliga im Juli um Punkte? | Fussball-Fragen","headline":"Wie oft spielte der Hamburger SV in der Bundesliga im Juli um Punkte?","author":{"@id":"https:\/\/www.fussball-fragen.de\/index.php\/author\/ff-admin\/#author"},"publisher":{"@id":"https:\/\/www.fussball-fragen.de\/#organization"},"datePublished":"2013-07-19T14:58:58+02:00","dateModified":"2013-07-20T12:18:05+02:00","inLanguage":"de-DE","mainEntityOfPage":{"@id":"https:\/\/www.fussball-fragen.de\/index.php\/bundesliga\/wie-oft-spielte-der-hamburger-sv-in-der-bundesliga-im-juli-um-punkte\/#webpage"},"isPartOf":{"@id":"https:\/\/www.fussball-fragen.de\/index.php\/bundesliga\/wie-oft-spielte-der-hamburger-sv-in-der-bundesliga-im-juli-um-punkte\/#webpage"},"articleSection":"Bundesliga, Bundesliga, Hamburger SV, HSV, Spiele"},{"@type":"BreadcrumbList","@id":"https:\/\/www.fussball-fragen.de\/index.php\/bundesliga\/wie-oft-spielte-der-hamburger-sv-in-der-bundesliga-im-juli-um-punkte\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.fussball-fragen.de#listItem","position":1,"name":"Home","item":"https:\/\/www.fussball-fragen.de","nextItem":{"@type":"ListItem","@id":"https:\/\/www.fussball-fragen.de\/index.php\/category\/bundesliga\/#listItem","name":"Bundesliga"}},{"@type":"ListItem","@id":"https:\/\/www.fussball-fragen.de\/index.php\/category\/bundesliga\/#listItem","position":2,"name":"Bundesliga","item":"https:\/\/www.fussball-fragen.de\/index.php\/category\/bundesliga\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.fussball-fragen.de\/index.php\/bundesliga\/wie-oft-spielte-der-hamburger-sv-in-der-bundesliga-im-juli-um-punkte\/#listItem","name":"Wie oft spielte der Hamburger SV in der Bundesliga im Juli um Punkte?"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.fussball-fragen.de#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.fussball-fragen.de\/index.php\/bundesliga\/wie-oft-spielte-der-hamburger-sv-in-der-bundesliga-im-juli-um-punkte\/#listItem","position":3,"name":"Wie oft spielte der Hamburger SV in der Bundesliga im Juli um Punkte?","previousItem":{"@type":"ListItem","@id":"https:\/\/www.fussball-fragen.de\/index.php\/category\/bundesliga\/#listItem","name":"Bundesliga"}}]},{"@type":"Organization","@id":"https:\/\/www.fussball-fragen.de\/#organization","name":"Fussball-Fragen","description":"Sinnvolles und sinnloses (Halb)wissen rund um den Fu\u00dfball.","url":"https:\/\/www.fussball-fragen.de\/"},{"@type":"Person","@id":"https:\/\/www.fussball-fragen.de\/index.php\/author\/ff-admin\/#author","url":"https:\/\/www.fussball-fragen.de\/index.php\/author\/ff-admin\/","name":"ff-admin","image":{"@type":"ImageObject","@id":"https:\/\/www.fussball-fragen.de\/index.php\/bundesliga\/wie-oft-spielte-der-hamburger-sv-in-der-bundesliga-im-juli-um-punkte\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/a8b0a04952980de24adc2a8820b0c592?s=96&d=mm&r=g","width":96,"height":96,"caption":"ff-admin"}},{"@type":"WebPage","@id":"https:\/\/www.fussball-fragen.de\/index.php\/bundesliga\/wie-oft-spielte-der-hamburger-sv-in-der-bundesliga-im-juli-um-punkte\/#webpage","url":"https:\/\/www.fussball-fragen.de\/index.php\/bundesliga\/wie-oft-spielte-der-hamburger-sv-in-der-bundesliga-im-juli-um-punkte\/","name":"Wie oft spielte der Hamburger SV in der Bundesliga im Juli um Punkte? | Fussball-Fragen","description":"Frage: Wie oft spielte HSV in der Bundesliga im Juli um Punkte? Antwort: Insgesamt nur 4x in der 50j\u00e4hrigen Bundesligazugeh\u00f6rigkeit (bei insgesamt 1696 Spielen in dieser Zeit): Saison 1988\/1989 Spieltag 1 (Sa. 23.07.1988) Werder Bremen - Hamburger SV 2:1 Spieltag 2 (Fr. 29.07.1988) Hamburger SV - Borussia Dortmund 0:0 Saison 1989\/90 Spieltag 1 (Sa. 29.07.1989)","inLanguage":"de-DE","isPartOf":{"@id":"https:\/\/www.fussball-fragen.de\/#website"},"breadcrumb":{"@id":"https:\/\/www.fussball-fragen.de\/index.php\/bundesliga\/wie-oft-spielte-der-hamburger-sv-in-der-bundesliga-im-juli-um-punkte\/#breadcrumblist"},"author":{"@id":"https:\/\/www.fussball-fragen.de\/index.php\/author\/ff-admin\/#author"},"creator":{"@id":"https:\/\/www.fussball-fragen.de\/index.php\/author\/ff-admin\/#author"},"datePublished":"2013-07-19T14:58:58+02:00","dateModified":"2013-07-20T12:18:05+02:00"},{"@type":"WebSite","@id":"https:\/\/www.fussball-fragen.de\/#website","url":"https:\/\/www.fussball-fragen.de\/","name":"Fussball-Fragen","description":"Sinnvolles und sinnloses (Halb)wissen rund um den Fu\u00dfball.","inLanguage":"de-DE","publisher":{"@id":"https:\/\/www.fussball-fragen.de\/#organization"}}]},"og:locale":"de_DE","og:site_name":"Fussball-Fragen","og:type":"blog","og:title":"Wie oft spielte der Hamburger SV in der Bundesliga im Juli um Punkte? | Fussball-Fragen","og:description":"Frage: Wie oft spielte HSV in der Bundesliga im Juli um Punkte? Antwort: Insgesamt nur 4x in der 50j\u00e4hrigen Bundesligazugeh\u00f6rigkeit (bei insgesamt 1696 Spielen in dieser Zeit): Saison 1988\/1989 Spieltag 1 (Sa. 23.07.1988) Werder Bremen - Hamburger SV 2:1 Spieltag 2 (Fr. 29.07.1988) Hamburger SV - Borussia Dortmund 0:0 Saison 1989\/90 Spieltag 1 (Sa. 29.07.1989)","og:url":"https:\/\/www.fussball-fragen.de\/index.php\/bundesliga\/wie-oft-spielte-der-hamburger-sv-in-der-bundesliga-im-juli-um-punkte\/","twitter:card":"summary","twitter:title":"Wie oft spielte der Hamburger SV in der Bundesliga im Juli um Punkte? | Fussball-Fragen","twitter:description":"Frage: Wie oft spielte HSV in der Bundesliga im Juli um Punkte? Antwort: Insgesamt nur 4x in der 50j\u00e4hrigen Bundesligazugeh\u00f6rigkeit (bei insgesamt 1696 Spielen in dieser Zeit): Saison 1988\/1989 Spieltag 1 (Sa. 23.07.1988) Werder Bremen - Hamburger SV 2:1 Spieltag 2 (Fr. 29.07.1988) Hamburger SV - Borussia Dortmund 0:0 Saison 1989\/90 Spieltag 1 (Sa. 29.07.1989)"},"aioseo_meta_data":{"post_id":"1486","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2021-12-24 14:10:13","updated":"2022-09-14 22:21:03","seo_analyzer_scan_date":null,"focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.fussball-fragen.de\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.fussball-fragen.de\/index.php\/category\/bundesliga\/\" title=\"Bundesliga\">Bundesliga<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tWie oft spielte der Hamburger SV in der Bundesliga im Juli um Punkte?\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.fussball-fragen.de"},{"label":"Bundesliga","link":"https:\/\/www.fussball-fragen.de\/index.php\/category\/bundesliga\/"},{"label":"Wie oft spielte der Hamburger SV in der Bundesliga im Juli um Punkte?","link":"https:\/\/www.fussball-fragen.de\/index.php\/bundesliga\/wie-oft-spielte-der-hamburger-sv-in-der-bundesliga-im-juli-um-punkte\/"}],"views":2055,"_links":{"self":[{"href":"https:\/\/www.fussball-fragen.de\/index.php\/wp-json\/wp\/v2\/posts\/1486"}],"collection":[{"href":"https:\/\/www.fussball-fragen.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fussball-fragen.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fussball-fragen.de\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fussball-fragen.de\/index.php\/wp-json\/wp\/v2\/comments?post=1486"}],"version-history":[{"count":1,"href":"https:\/\/www.fussball-fragen.de\/index.php\/wp-json\/wp\/v2\/posts\/1486\/revisions"}],"predecessor-version":[{"id":1487,"href":"https:\/\/www.fussball-fragen.de\/index.php\/wp-json\/wp\/v2\/posts\/1486\/revisions\/1487"}],"wp:attachment":[{"href":"https:\/\/www.fussball-fragen.de\/index.php\/wp-json\/wp\/v2\/media?parent=1486"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fussball-fragen.de\/index.php\/wp-json\/wp\/v2\/categories?post=1486"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fussball-fragen.de\/index.php\/wp-json\/wp\/v2\/tags?post=1486"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}